{"id":465,"date":"2024-07-20T05:39:16","date_gmt":"2024-07-20T05:39:16","guid":{"rendered":"https:\/\/thelanguagetrade.com\/?page_id=465"},"modified":"2024-07-20T05:39:16","modified_gmt":"2024-07-20T05:39:16","slug":"registration","status":"publish","type":"page","link":"https:\/\/thelanguagetrade.com\/index.php\/registration\/","title":{"rendered":"Registration"},"content":{"rendered":"<style id=\"wpforms-css-vars-444-block-8c3f0808-1b77-4d08-bd65-0e028625540f\">\n\t\t\t\t#wpforms-444.wpforms-block-8c3f0808-1b77-4d08-bd65-0e028625540f {\n\t\t\t\t--wpforms-field-border-style: dotted;\n--wpforms-button-background-color: #0B0C10;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 14px;\n--wpforms-label-size-line-height: 17px;\n--wpforms-label-size-sublabel-font-size: 13px;\n--wpforms-label-size-sublabel-line-height: 16px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-8c3f0808-1b77-4d08-bd65-0e028625540f wpforms-render-modern\" id=\"wpforms-444\"><form id=\"wpforms-form-444\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"444\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/465\" data-token=\"4e9f44d81b45627d26066a71cabbdbe0\" data-token-time=\"1778672812\"><div class=\"wpforms-head-container\"><div class=\"wpforms-title\">Registration Form<\/div><\/div><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-444-field_10-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-444-field_10\">Company Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-444-field_10\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][10]\" aria-errormessage=\"wpforms-444-field_10-error\" required><\/div><div id=\"wpforms-444-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-444-field_2\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-444-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-444-field_2-error\" required><\/div><div id=\"wpforms-444-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-444-field_3\">Skype Id <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-444-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-444-field_3-error\" required><\/div><div id=\"wpforms-444-field_8-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"8\"><fieldset><legend class=\"wpforms-field-label\">Your Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-444-field_8\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][8][first]\" aria-errormessage=\"wpforms-444-field_8-error\" required><label for=\"wpforms-444-field_8\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-444-field_8-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][8][last]\" aria-errormessage=\"wpforms-444-field_8-last-error\" required><label for=\"wpforms-444-field_8-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-444-field_9-container\" class=\"wpforms-field wpforms-field-payment-select wpforms-field-select-style-classic\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-444-field_9\">Choose <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-444-field_9\" class=\"wpforms-payment-price wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" required=\"required\"><option value=\"1\" data-amount=\"0.00\" >Advertiser<\/option><option value=\"2\" data-amount=\"0.00\" >Publisher<\/option><\/select><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"444\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/thelanguagetrade.com\/index.php\/wp-json\/wp\/v2\/pages\/465\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-444\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img decoding=\"async\" src=\"https:\/\/thelanguagetrade.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-465","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/thelanguagetrade.com\/index.php\/wp-json\/wp\/v2\/pages\/465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thelanguagetrade.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thelanguagetrade.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thelanguagetrade.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/thelanguagetrade.com\/index.php\/wp-json\/wp\/v2\/comments?post=465"}],"version-history":[{"count":1,"href":"https:\/\/thelanguagetrade.com\/index.php\/wp-json\/wp\/v2\/pages\/465\/revisions"}],"predecessor-version":[{"id":468,"href":"https:\/\/thelanguagetrade.com\/index.php\/wp-json\/wp\/v2\/pages\/465\/revisions\/468"}],"wp:attachment":[{"href":"https:\/\/thelanguagetrade.com\/index.php\/wp-json\/wp\/v2\/media?parent=465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}